{"id":2920,"date":"2024-07-05T01:00:00","date_gmt":"2024-07-05T04:00:00","guid":{"rendered":"https:\/\/www.oracaoefe.com\/?p=2920"},"modified":"2024-07-02T20:36:53","modified_gmt":"2024-07-02T23:36:53","slug":"el-arca-de-noe-3-curiosidades-que-no-sabias","status":"publish","type":"post","link":"https:\/\/www.oracaoefe.com\/es\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/","title":{"rendered":"El Arca de No\u00e9: 3 curiosidades que no sab\u00edas"},"content":{"rendered":"<p>La historia del Arca de No\u00e9 es uno de los relatos b\u00edblicos m\u00e1s conocidos y fascinantes, que ha cautivado la imaginaci\u00f3n de la gente durante siglos. Detr\u00e1s de esta historia hay detalles curiosos y a menudo menos conocidos que a\u00f1aden capas a nuestra comprensi\u00f3n de este relato \u00e9pico.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Curiosidades que no sab\u00edas sobre el Arca de No\u00e9<\/h2>\n\n\n\n<p>La idea de que un hombre construyera un enorme barco para salvar a su familia y a varias especies de animales del diluvio es tan intrigante como inspiradora. He aqu\u00ed 3 datos fascinantes sobre el Arca de No\u00e9 que probablemente no conoc\u00edas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Dimensiones del t\u00f3rax<\/h3>\n\n\n\n<p>Cuando pensamos en el Arca de No\u00e9, muchos nos imaginamos una gran embarcaci\u00f3n, pero rara vez nos detenemos a considerar sus dimensiones concretas. Seg\u00fan el relato b\u00edblico del libro del G\u00e9nesis, el Arca ten\u00eda unas dimensiones impresionantes: 300 codos de largo, 50 codos de ancho y 30 codos de alto.&nbsp;<\/p>\n\n\n\n<p>Para quienes no est\u00e9n familiarizados con el codo, se trata de una unidad de longitud com\u00fan en la antig\u00fcedad, que equivale aproximadamente a entre 45 y 52 cent\u00edmetros. Por lo tanto, calculando estas medidas en unidades modernas, el Arca habr\u00eda medido unos 135 metros de largo, 22,5 metros de ancho y 13,5 metros de alto.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"415\" src=\"https:\/\/www.oracaoefe.com\/wp-content\/uploads\/2024\/07\/image-1.png\" alt=\"\" class=\"wp-image-2932\" style=\"width:840px;height:auto\" srcset=\"https:\/\/www.oracaoefe.com\/wp-content\/uploads\/2024\/07\/image-1.png 740w, https:\/\/www.oracaoefe.com\/wp-content\/uploads\/2024\/07\/image-1-300x168.png 300w, https:\/\/www.oracaoefe.com\/wp-content\/uploads\/2024\/07\/image-1-18x10.png 18w, https:\/\/www.oracaoefe.com\/wp-content\/uploads\/2024\/07\/image-1-350x195.png 350w, https:\/\/www.oracaoefe.com\/wp-content\/uploads\/2024\/07\/image-1-383x215.png 383w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<p>Estas dimensiones sit\u00faan al Arca de No\u00e9 en una escala impresionante para su \u00e9poca, capaz de albergar una importante cantidad de carga, incluidos animales de todo tipo, as\u00ed como provisiones para sobrevivir durante el diluvio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Construir el arca<\/h3>\n\n\n\n<p>La construcci\u00f3n del Arca de No\u00e9 es otro aspecto intrigante de la historia. Seg\u00fan el relato b\u00edblico, Dios orden\u00f3 a No\u00e9 que construyera el Arca para salvar a su familia y a representantes de todas las especies de animales terrestres.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, la tarea de construir un buque de tal magnitud no era trivial, sobre todo teniendo en cuenta los recursos disponibles en la \u00e9poca.<\/p>\n\n\n\n<p>No\u00e9 recibi\u00f3 instrucciones de construir el Arca con madera de topo, una especie de madera que hoy no est\u00e1 claramente identificada. Es interesante observar que la palabra hebrea traducida como \"topo\" puede significar \"cubrir\" o \"revestir\", lo que indica que la madera podr\u00eda haber sido tratada o revestida para protegerla del agua.&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s, No\u00e9 recibi\u00f3 instrucciones detalladas sobre el dise\u00f1o del Arca, incluida la divisi\u00f3n interna en tres pisos y la inclusi\u00f3n de una ventana y una puerta.<\/p>\n\n\n\n<p>La construcci\u00f3n del Arca llev\u00f3 mucho tiempo; seg\u00fan algunas interpretaciones, No\u00e9 tard\u00f3 aproximadamente 120 a\u00f1os en completar la construcci\u00f3n seg\u00fan las instrucciones divinas.&nbsp;<\/p>\n\n\n\n<p>Este prolongado periodo puede ser indicativo de la escala monumental del proyecto y de la perseverancia de No\u00e9 ante las dificultades y la incredulidad de quienes le rodeaban.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. El prop\u00f3sito del arca<\/h3>\n\n\n\n<p>Adem\u00e1s de servir para preservar la vida durante el diluvio, el Arca de No\u00e9 tiene profundos significados simb\u00f3licos y teol\u00f3gicos dentro de la tradici\u00f3n judeocristiana.&nbsp;<\/p>\n\n\n\n<p>En primer lugar, el Arca se considera un s\u00edmbolo de salvaci\u00f3n y protecci\u00f3n divina. Mientras que el diluvio devast\u00f3 la tierra a causa de la corrupci\u00f3n y la violencia humanas, el Arca representaba un lugar de seguridad y esperanza para quienes encontraban refugio en ella.<\/p>\n\n\n\n<p>Tambi\u00e9n se interpreta a menudo como una especie de prefiguraci\u00f3n del bautismo cristiano. Al igual que el agua del diluvio trajo el juicio y la purificaci\u00f3n a la tierra, el bautismo se considera un acto de purificaci\u00f3n espiritual y de renovaci\u00f3n de la vida en Cristo.<\/p>\n\n\n\n<p>Otra interpretaci\u00f3n interesante es que puede considerarse precursora del templo jud\u00edo. As\u00ed como el templo era el lugar donde la presencia de Dios habitaba entre el pueblo de Israel, el Arca era el lugar donde la presencia de Dios se manifestaba durante el diluvio, protegiendo y preservando la vida seg\u00fan el plan de Dios.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Historia del Arca de No\u00e9<\/h2>\n\n\n\n<p>La historia del Arca de No\u00e9 va mucho m\u00e1s all\u00e1 de una simple narraci\u00f3n infantil. Ofrece una visi\u00f3n profunda de la naturaleza humana, la providencia divina y la importancia de la obediencia y la fe.&nbsp;<\/p>\n\n\n\n<p>Al explorar sus impresionantes dimensiones, la complejidad de su construcci\u00f3n y los significados simb\u00f3licos que encierra, nos lleva a reflexionar sobre temas universales como la supervivencia, la renovaci\u00f3n y la redenci\u00f3n.<\/p>\n\n\n\n<p>Aunque algunos detalles de la historia sigan envueltos en el misterio y el debate, el mensaje central del Arca de No\u00e9 sigue resonando a trav\u00e9s de los tiempos: la promesa de protecci\u00f3n divina para quienes conf\u00edan en Dios y siguen sus caminos.&nbsp;<\/p>\n\n\n\n<p>Que esta historia siga inspirando y desafiando a personas de todas las culturas y \u00e9pocas, record\u00e1ndonos la importancia de cuidar la creaci\u00f3n y vivir en armon\u00eda con la voluntad de Dios.<\/p>\n\n\n\n<p><p><strong>V\u00e9ase tambi\u00e9n: <a href=\"https:\/\/www.oracaoefe.com\/es\/oraciones-para-la-proteccion-y-la-salud-durante-el-embarazo\/\">Oraci\u00f3n por la protecci\u00f3n y la salud durante el embarazo<\/a><\/strong><\/p><\/p>\n\n\n\n<p><p>5 de julio de 2024<\/p> <\/p>","protected":false},"excerpt":{"rendered":"<p>A hist\u00f3ria da Arca de No\u00e9 \u00e9 uma das mais conhecidas e fascinantes narrativas b\u00edblicas, que tem capturado a imagina\u00e7\u00e3o das pessoas ao longo dos s\u00e9culos. Por tr\u00e1s dessa hist\u00f3ria, existem detalhes curiosos e muitas vezes menos conhecidos que adicionam camadas \u00e0 nossa compreens\u00e3o deste \u00e9pico relato.&nbsp; Curiosidades que voc\u00ea n\u00e3o sabia sobre a Arca&hellip;&nbsp;<\/p>","protected":false},"author":3,"featured_media":2932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[1],"tags":[83],"class_list":["post-2920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-biblia-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arca de No\u00e9: 3 curiosidades que voc\u00ea n\u00e3o sabia - Ora\u00e7\u00e3o e F\u00e9<\/title>\n<meta name=\"description\" content=\"Deus tem pra voc\u00ea uma palavra de vida!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oracaoefe.com\/es\/el-arca-de-noe-3-curiosidades-que-no-sabias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arca de No\u00e9: 3 curiosidades que voc\u00ea n\u00e3o sabia - Ora\u00e7\u00e3o e F\u00e9\" \/>\n<meta property=\"og:description\" content=\"Deus tem pra voc\u00ea uma palavra de vida!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oracaoefe.com\/es\/el-arca-de-noe-3-curiosidades-que-no-sabias\/\" \/>\n<meta property=\"og:site_name\" content=\"Ora\u00e7\u00e3o e F\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-05T04:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.oracaoefe.com\/wp-content\/uploads\/2024\/07\/image-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"740\" \/>\n\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Michele Azevedo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michele Azevedo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\\\/\"},\"author\":{\"name\":\"Michele Azevedo\",\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/#\\\/schema\\\/person\\\/17283c669442cf005c4d5bb58adfb7f5\"},\"headline\":\"Arca de No\u00e9: 3 curiosidades que voc\u00ea n\u00e3o sabia\",\"datePublished\":\"2024-07-05T04:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\\\/\"},\"wordCount\":853,\"image\":{\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.oracaoefe.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/image-1.png\",\"keywords\":[\"B\u00edblia\"],\"articleSection\":[\"Curiosidades\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\\\/\",\"url\":\"https:\\\/\\\/www.oracaoefe.com\\\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\\\/\",\"name\":\"Arca de No\u00e9: 3 curiosidades que voc\u00ea n\u00e3o sabia - Ora\u00e7\u00e3o e F\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.oracaoefe.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/image-1.png\",\"datePublished\":\"2024-07-05T04:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/#\\\/schema\\\/person\\\/17283c669442cf005c4d5bb58adfb7f5\"},\"description\":\"Deus tem pra voc\u00ea uma palavra de vida!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.oracaoefe.com\\\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.oracaoefe.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/image-1.png\",\"contentUrl\":\"https:\\\/\\\/www.oracaoefe.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/image-1.png\",\"width\":740,\"height\":415},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.oracaoefe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curiosidades\",\"item\":\"https:\\\/\\\/www.oracaoefe.com\\\/es\\\/categoria\\\/curiosidades\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arca de No\u00e9: 3 curiosidades que voc\u00ea n\u00e3o sabia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/#website\",\"url\":\"https:\\\/\\\/www.oracaoefe.com\\\/\",\"name\":\"Ora\u00e7\u00e3o e F\u00e9\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.oracaoefe.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/#\\\/schema\\\/person\\\/17283c669442cf005c4d5bb58adfb7f5\",\"name\":\"Michele Azevedo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b0eb9d22841282815e2cd856a0061c45e1761cd54b22e952d98c4746939aa85?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b0eb9d22841282815e2cd856a0061c45e1761cd54b22e952d98c4746939aa85?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b0eb9d22841282815e2cd856a0061c45e1761cd54b22e952d98c4746939aa85?s=96&d=mm&r=g\",\"caption\":\"Michele Azevedo\"},\"description\":\"Formada em Letras - Portugu\u00eas\\\/ Ingl\u00eas pela Universidade Estadual de Ponta Grossa (UEPG), p\u00f3s-graduada em Arte na Educa\u00e7\u00e3o (FAPI) e Psicopedagogia Escolar (FAPI), idealizadora e propriet\u00e1ria do site Escritora de Sucesso, possui experi\u00eancia em escrita para blogs em geral e atua como redatora e revisora dos conte\u00fados do Ora\u00e7\u00e3o e F\u00e9.\",\"url\":\"https:\\\/\\\/www.oracaoefe.com\\\/es\\\/author\\\/michele-azevedo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Arca de No\u00e9: 3 curiosidades que no sab\u00edas - Oraci\u00f3n y Fe","description":"\u00a1Dios tiene una palabra de vida para ti!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oracaoefe.com\/es\/el-arca-de-noe-3-curiosidades-que-no-sabias\/","og_locale":"es_ES","og_type":"article","og_title":"Arca de No\u00e9: 3 curiosidades que voc\u00ea n\u00e3o sabia - Ora\u00e7\u00e3o e F\u00e9","og_description":"Deus tem pra voc\u00ea uma palavra de vida!","og_url":"https:\/\/www.oracaoefe.com\/es\/el-arca-de-noe-3-curiosidades-que-no-sabias\/","og_site_name":"Ora\u00e7\u00e3o e F\u00e9","article_published_time":"2024-07-05T04:00:00+00:00","og_image":[{"width":740,"height":415,"url":"https:\/\/www.oracaoefe.com\/wp-content\/uploads\/2024\/07\/image-1.png","type":"image\/png"}],"author":"Michele Azevedo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Michele Azevedo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.oracaoefe.com\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/#article","isPartOf":{"@id":"https:\/\/www.oracaoefe.com\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/"},"author":{"name":"Michele Azevedo","@id":"https:\/\/www.oracaoefe.com\/#\/schema\/person\/17283c669442cf005c4d5bb58adfb7f5"},"headline":"Arca de No\u00e9: 3 curiosidades que voc\u00ea n\u00e3o sabia","datePublished":"2024-07-05T04:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.oracaoefe.com\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/"},"wordCount":853,"image":{"@id":"https:\/\/www.oracaoefe.com\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oracaoefe.com\/wp-content\/uploads\/2024\/07\/image-1.png","keywords":["B\u00edblia"],"articleSection":["Curiosidades"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.oracaoefe.com\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/","url":"https:\/\/www.oracaoefe.com\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/","name":"El Arca de No\u00e9: 3 curiosidades que no sab\u00edas - Oraci\u00f3n y Fe","isPartOf":{"@id":"https:\/\/www.oracaoefe.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.oracaoefe.com\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/#primaryimage"},"image":{"@id":"https:\/\/www.oracaoefe.com\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oracaoefe.com\/wp-content\/uploads\/2024\/07\/image-1.png","datePublished":"2024-07-05T04:00:00+00:00","author":{"@id":"https:\/\/www.oracaoefe.com\/#\/schema\/person\/17283c669442cf005c4d5bb58adfb7f5"},"description":"\u00a1Dios tiene una palabra de vida para ti!","breadcrumb":{"@id":"https:\/\/www.oracaoefe.com\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oracaoefe.com\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oracaoefe.com\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/#primaryimage","url":"https:\/\/www.oracaoefe.com\/wp-content\/uploads\/2024\/07\/image-1.png","contentUrl":"https:\/\/www.oracaoefe.com\/wp-content\/uploads\/2024\/07\/image-1.png","width":740,"height":415},{"@type":"BreadcrumbList","@id":"https:\/\/www.oracaoefe.com\/arca-de-noe-3-curiosidades-que-voce-nao-sabia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.oracaoefe.com\/"},{"@type":"ListItem","position":2,"name":"Curiosidades","item":"https:\/\/www.oracaoefe.com\/es\/categoria\/curiosidades\/"},{"@type":"ListItem","position":3,"name":"Arca de No\u00e9: 3 curiosidades que voc\u00ea n\u00e3o sabia"}]},{"@type":"WebSite","@id":"https:\/\/www.oracaoefe.com\/#website","url":"https:\/\/www.oracaoefe.com\/","name":"Oraci\u00f3n y fe","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oracaoefe.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.oracaoefe.com\/#\/schema\/person\/17283c669442cf005c4d5bb58adfb7f5","name":"Michele Azevedo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6b0eb9d22841282815e2cd856a0061c45e1761cd54b22e952d98c4746939aa85?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6b0eb9d22841282815e2cd856a0061c45e1761cd54b22e952d98c4746939aa85?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0eb9d22841282815e2cd856a0061c45e1761cd54b22e952d98c4746939aa85?s=96&d=mm&r=g","caption":"Michele Azevedo"},"description":"Formada em Letras - Portugu\u00eas\/ Ingl\u00eas pela Universidade Estadual de Ponta Grossa (UEPG), p\u00f3s-graduada em Arte na Educa\u00e7\u00e3o (FAPI) e Psicopedagogia Escolar (FAPI), idealizadora e propriet\u00e1ria do site Escritora de Sucesso, possui experi\u00eancia em escrita para blogs em geral e atua como redatora e revisora dos conte\u00fados do Ora\u00e7\u00e3o e F\u00e9.","url":"https:\/\/www.oracaoefe.com\/es\/author\/michele-azevedo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.oracaoefe.com\/es\/wp-json\/wp\/v2\/posts\/2920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oracaoefe.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oracaoefe.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oracaoefe.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oracaoefe.com\/es\/wp-json\/wp\/v2\/comments?post=2920"}],"version-history":[{"count":2,"href":"https:\/\/www.oracaoefe.com\/es\/wp-json\/wp\/v2\/posts\/2920\/revisions"}],"predecessor-version":[{"id":2933,"href":"https:\/\/www.oracaoefe.com\/es\/wp-json\/wp\/v2\/posts\/2920\/revisions\/2933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oracaoefe.com\/es\/wp-json\/wp\/v2\/media\/2932"}],"wp:attachment":[{"href":"https:\/\/www.oracaoefe.com\/es\/wp-json\/wp\/v2\/media?parent=2920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oracaoefe.com\/es\/wp-json\/wp\/v2\/categories?post=2920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oracaoefe.com\/es\/wp-json\/wp\/v2\/tags?post=2920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}