{"id":171,"count":1,"description":"","link":"https:\/\/www.oracaoefe.com\/en\/tag\/copa-do-mundo\/","name":"world cup","slug":"world-cup","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>copa do mundo Archives - Ora\u00e7\u00e3o e F\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oracaoefe.com\/en\/tag\/world-cup\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"copa do mundo Archives - Ora\u00e7\u00e3o e F\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oracaoefe.com\/en\/tag\/world-cup\/\" \/>\n<meta property=\"og:site_name\" content=\"Ora\u00e7\u00e3o e F\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/tag\\\/copa-do-mundo\\\/\",\"url\":\"https:\\\/\\\/www.oracaoefe.com\\\/tag\\\/copa-do-mundo\\\/\",\"name\":\"copa do mundo Archives - Ora\u00e7\u00e3o e F\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/tag\\\/copa-do-mundo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/tag\\\/copa-do-mundo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.oracaoefe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"copa do mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.oracaoefe.com\\\/#website\",\"url\":\"https:\\\/\\\/www.oracaoefe.com\\\/\",\"name\":\"Ora\u00e7\u00e3o e F\u00e9\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.oracaoefe.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"copa do mundo Archives - Ora\u00e7\u00e3o e F\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oracaoefe.com\/en\/tag\/world-cup\/","og_locale":"en_US","og_type":"article","og_title":"copa do mundo Archives - Ora\u00e7\u00e3o e F\u00e9","og_url":"https:\/\/www.oracaoefe.com\/en\/tag\/world-cup\/","og_site_name":"Ora\u00e7\u00e3o e F\u00e9","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.oracaoefe.com\/tag\/copa-do-mundo\/","url":"https:\/\/www.oracaoefe.com\/tag\/copa-do-mundo\/","name":"world cup Archives - Prayer and Faith","isPartOf":{"@id":"https:\/\/www.oracaoefe.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.oracaoefe.com\/tag\/copa-do-mundo\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.oracaoefe.com\/tag\/copa-do-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.oracaoefe.com\/"},{"@type":"ListItem","position":2,"name":"copa do mundo"}]},{"@type":"WebSite","@id":"https:\/\/www.oracaoefe.com\/#website","url":"https:\/\/www.oracaoefe.com\/","name":"Prayer and Faith","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oracaoefe.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.oracaoefe.com\/en\/wp-json\/wp\/v2\/tags\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oracaoefe.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.oracaoefe.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.oracaoefe.com\/en\/wp-json\/wp\/v2\/posts?tags=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}